{"id":7028,"date":"2020-07-07T18:19:53","date_gmt":"2020-07-07T17:19:53","guid":{"rendered":"https:\/\/steinzauber-online.de\/?post_type=product&#038;p=7028"},"modified":"2025-05-14T12:54:52","modified_gmt":"2025-05-14T11:54:52","slug":"kugelkette-tuerkis-rekonstruiert-45-cm-kopie","status":"publish","type":"product","link":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/","title":{"rendered":"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm"},"content":{"rendered":"<div class=\"widgetBoxBottomRound\">\n<div id=\"description\" class=\"cmsContent ui-tabs-panel ui-widget-content ui-corner-bottom\">\n<div class=\"tabbedWidgetBox clear ui-tabs ui-widget ui-widget-content ui-corner-all\">\n<div class=\"widgetBoxBottomRound\">\n<div id=\"description\" class=\"cmsContent ui-tabs-panel ui-widget-content ui-corner-bottom\">\n<p>Kugelkette in T\u00fcrkis (rekonstruiert) mit einer L\u00e4nge von ca. 45 cm. Die Gr\u00f6\u00dfe der Kugeln betr\u00e4gt 6 mm.\u00a0 Gehalten wird die Kette von einem Karabinerverschluss.<\/p>\n<p>Bitte fahren Sie mit der Maus \u00fcber das Foto, um eine Vergr\u00f6\u00dferung des Fotos zu erhalten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kugelkette in T\u00fcrkis (rekonstruiert) mit einer L\u00e4nge von ca. 45 cm. Die Gr\u00f6\u00dfe der Kugeln betr\u00e4gt 6 mm.\u00a0 Gehalten wird die Kette von einem Karabinerverschluss. Bitte fahren Sie mit der Maus \u00fcber das Foto, um eine Vergr\u00f6\u00dferung des Fotos zu erhalten.<\/p>\n","protected":false},"featured_media":7036,"template":"","meta":[],"product_brand":[],"product_cat":[80,603],"product_tag":[142,534,782,780,236],"class_list":{"0":"post-7028","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kugelketten","7":"product_cat-neue-artikel-bei-steinzauber","8":"product_tag-edelsteine","9":"product_tag-edelsteinkette","10":"product_tag-edelsteinkugelkette","11":"product_tag-kugelkette","12":"product_tag-tuerkis","14":"first","15":"outofstock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm - Steinzauber\u00ae<\/title>\n<meta name=\"description\" content=\"Splitterkette T\u00fcrkis (rekonstruiert) Splitterkette 45 cm. Sehr sch\u00f6ne Splitterkette aus rekonstruierten T\u00fcrkis-Splittern mit einer L\u00e4nge von 45 cm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm - Steinzauber\u00ae\" \/>\n<meta property=\"og:description\" content=\"Splitterkette T\u00fcrkis (rekonstruiert) Splitterkette 45 cm. Sehr sch\u00f6ne Splitterkette aus rekonstruierten T\u00fcrkis-Splittern mit einer L\u00e4nge von 45 cm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/\" \/>\n<meta property=\"og:site_name\" content=\"Steinzauber\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/Steinzauber\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T11:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/07\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/\",\"name\":\"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm - Steinzauber\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg\",\"datePublished\":\"2020-07-07T17:19:53+00:00\",\"dateModified\":\"2025-05-14T11:54:52+00:00\",\"description\":\"Splitterkette T\u00fcrkis (rekonstruiert) Splitterkette 45 cm. Sehr sch\u00f6ne Splitterkette aus rekonstruierten T\u00fcrkis-Splittern mit einer L\u00e4nge von 45 cm.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg\",\"width\":800,\"height\":800,\"caption\":\"Kugelkette T\u00fcrkis rekonstruiert 45 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"name\":\"Steinzauber\u00ae\",\"description\":\"Schmuck aus edlem Stein\",\"publisher\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/steinzauber-online.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\",\"name\":\"Steinzauber\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"width\":500,\"height\":262,\"caption\":\"Steinzauber\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/Steinzauber\\\/\",\"https:\\\/\\\/instagram.com\\\/steinzauber_schmuck?igshid=1fr2q2be784ld\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm - Steinzauber\u00ae","description":"Splitterkette T\u00fcrkis (rekonstruiert) Splitterkette 45 cm. Sehr sch\u00f6ne Splitterkette aus rekonstruierten T\u00fcrkis-Splittern mit einer L\u00e4nge von 45 cm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/","og_locale":"de_DE","og_type":"article","og_title":"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm - Steinzauber\u00ae","og_description":"Splitterkette T\u00fcrkis (rekonstruiert) Splitterkette 45 cm. Sehr sch\u00f6ne Splitterkette aus rekonstruierten T\u00fcrkis-Splittern mit einer L\u00e4nge von 45 cm.","og_url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/","og_site_name":"Steinzauber\u00ae","article_publisher":"https:\/\/de-de.facebook.com\/Steinzauber\/","article_modified_time":"2025-05-14T11:54:52+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/07\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/","url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/","name":"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm - Steinzauber\u00ae","isPartOf":{"@id":"https:\/\/steinzauber-online.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/#primaryimage"},"image":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/#primaryimage"},"thumbnailUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/07\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg","datePublished":"2020-07-07T17:19:53+00:00","dateModified":"2025-05-14T11:54:52+00:00","description":"Splitterkette T\u00fcrkis (rekonstruiert) Splitterkette 45 cm. Sehr sch\u00f6ne Splitterkette aus rekonstruierten T\u00fcrkis-Splittern mit einer L\u00e4nge von 45 cm.","breadcrumb":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/#primaryimage","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/07\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/07\/Kugelkette_45cm_Tuerkis_rekonstruiert_KKHT455.jpg","width":800,"height":800,"caption":"Kugelkette T\u00fcrkis rekonstruiert 45 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/kugelkette-tuerkis-rekonstruiert-45-cm-kopie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/steinzauber-online.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/steinzauber-online.de\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Kugelkette 6 mm T\u00fcrkis (rekonstruiert) 45 cm"}]},{"@type":"WebSite","@id":"https:\/\/steinzauber-online.de\/#website","url":"https:\/\/steinzauber-online.de\/","name":"Steinzauber\u00ae","description":"Schmuck aus edlem Stein","publisher":{"@id":"https:\/\/steinzauber-online.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/steinzauber-online.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/steinzauber-online.de\/#organization","name":"Steinzauber","url":"https:\/\/steinzauber-online.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","width":500,"height":262,"caption":"Steinzauber"},"image":{"@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/Steinzauber\/","https:\/\/instagram.com\/steinzauber_schmuck?igshid=1fr2q2be784ld"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product\/7028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media\/7036"}],"wp:attachment":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media?parent=7028"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=7028"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=7028"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=7028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}