{"id":6945,"date":"2020-06-15T19:07:37","date_gmt":"2020-06-15T18:07:37","guid":{"rendered":"https:\/\/steinzauber-online.de\/?post_type=product&#038;p=6945"},"modified":"2025-05-14T12:54:52","modified_gmt":"2025-05-14T11:54:52","slug":"edelsteinarmband-gute-laune-aus-haematit-5","status":"publish","type":"product","link":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/","title":{"rendered":"Edelsteinarmband &#8218;Gute Laune&#8216; aus H\u00e4matit"},"content":{"rendered":"<div class=\"widgetBoxBottomRound\">\n<div id=\"description\" class=\"cmsContent ui-tabs-panel ui-widget-content ui-corner-bottom\">Das &#8218;Gute Laune&#8216; Edelsteinarmband aus farbenfroh bedampften H\u00e4matit und verschiedenen silberfarbenen H\u00e4matitelementen. Das 20 cm lange Armband wird verschlossen mit einem Karabiner aus 925 Sterlingsilber.<\/div>\n<div class=\"cmsContent ui-tabs-panel ui-widget-content ui-corner-bottom\">Bitte fahren Sie mit der Maus \u00fcber das Foto, um eine Vergr\u00f6\u00dferung des Fotos zu erhalten.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das &#8218;Gute Laune&#8216; Edelsteinarmband aus farbenfroh bedampften H\u00e4matit und verschiedenen silberfarbenen H\u00e4matitelementen. Das 20 cm lange Armband wird verschlossen mit einem Karabiner aus 925 Sterlingsilber. Bitte fahren Sie mit der Maus \u00fcber das Foto, um eine Vergr\u00f6\u00dferung des Fotos zu erhalten.<\/p>\n","protected":false},"featured_media":6946,"template":"","meta":[],"product_brand":[],"product_cat":[776,603],"product_tag":[201,200,84,778,98,203,30],"class_list":{"0":"post-6945","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gute-laune-armbaender","7":"product_cat-neue-artikel-bei-steinzauber","8":"product_tag-armband","9":"product_tag-edelsteinarmband","10":"product_tag-exclusiv","11":"product_tag-gute-laune","12":"product_tag-haematit","13":"product_tag-silber","14":"product_tag-sterlingsilber","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edelsteinarmband &#039;Gute Laune&#039; aus H\u00e4matit - Steinzauber\u00ae<\/title>\n<meta name=\"description\" content=\"Das &#039;Gute Laune&#039; Edelsteinarmband aus bedampften H\u00e4matit und verschiedenen H\u00e4matitelementen. Das 20 cm lange Armband hat einen Karabiner aus Silber.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edelsteinarmband &#039;Gute Laune&#039; aus H\u00e4matit - Steinzauber\u00ae\" \/>\n<meta property=\"og:description\" content=\"Das &#039;Gute Laune&#039; Edelsteinarmband aus bedampften H\u00e4matit und verschiedenen H\u00e4matitelementen. Das 20 cm lange Armband hat einen Karabiner aus Silber.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Steinzauber\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/Steinzauber\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T11:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/06\/Edelsteinarmband_Haematit_ABGL105.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/\",\"name\":\"Edelsteinarmband 'Gute Laune' aus H\u00e4matit - Steinzauber\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Edelsteinarmband_Haematit_ABGL105.jpg\",\"datePublished\":\"2020-06-15T18:07:37+00:00\",\"dateModified\":\"2025-05-14T11:54:52+00:00\",\"description\":\"Das 'Gute Laune' Edelsteinarmband aus bedampften H\u00e4matit und verschiedenen H\u00e4matitelementen. Das 20 cm lange Armband hat einen Karabiner aus Silber.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Edelsteinarmband_Haematit_ABGL105.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Edelsteinarmband_Haematit_ABGL105.jpg\",\"width\":800,\"height\":800,\"caption\":\"Gute Laune Armb\u00e4nder H\u00e4matit bunt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/edelsteinarmband-gute-laune-aus-haematit-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Edelsteinarmband &#8218;Gute Laune&#8216; aus H\u00e4matit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"name\":\"Steinzauber\u00ae\",\"description\":\"Schmuck aus edlem Stein\",\"publisher\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/steinzauber-online.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\",\"name\":\"Steinzauber\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"width\":500,\"height\":262,\"caption\":\"Steinzauber\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/Steinzauber\\\/\",\"https:\\\/\\\/instagram.com\\\/steinzauber_schmuck?igshid=1fr2q2be784ld\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edelsteinarmband 'Gute Laune' aus H\u00e4matit - Steinzauber\u00ae","description":"Das 'Gute Laune' Edelsteinarmband aus bedampften H\u00e4matit und verschiedenen H\u00e4matitelementen. Das 20 cm lange Armband hat einen Karabiner aus Silber.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/","og_locale":"de_DE","og_type":"article","og_title":"Edelsteinarmband 'Gute Laune' aus H\u00e4matit - Steinzauber\u00ae","og_description":"Das 'Gute Laune' Edelsteinarmband aus bedampften H\u00e4matit und verschiedenen H\u00e4matitelementen. Das 20 cm lange Armband hat einen Karabiner aus Silber.","og_url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/","og_site_name":"Steinzauber\u00ae","article_publisher":"https:\/\/de-de.facebook.com\/Steinzauber\/","article_modified_time":"2025-05-14T11:54:52+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/06\/Edelsteinarmband_Haematit_ABGL105.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/","url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/","name":"Edelsteinarmband 'Gute Laune' aus H\u00e4matit - Steinzauber\u00ae","isPartOf":{"@id":"https:\/\/steinzauber-online.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/#primaryimage"},"image":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/#primaryimage"},"thumbnailUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/06\/Edelsteinarmband_Haematit_ABGL105.jpg","datePublished":"2020-06-15T18:07:37+00:00","dateModified":"2025-05-14T11:54:52+00:00","description":"Das 'Gute Laune' Edelsteinarmband aus bedampften H\u00e4matit und verschiedenen H\u00e4matitelementen. Das 20 cm lange Armband hat einen Karabiner aus Silber.","breadcrumb":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/#primaryimage","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/06\/Edelsteinarmband_Haematit_ABGL105.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/06\/Edelsteinarmband_Haematit_ABGL105.jpg","width":800,"height":800,"caption":"Gute Laune Armb\u00e4nder H\u00e4matit bunt"},{"@type":"BreadcrumbList","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/edelsteinarmband-gute-laune-aus-haematit-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/steinzauber-online.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/steinzauber-online.de\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Edelsteinarmband &#8218;Gute Laune&#8216; aus H\u00e4matit"}]},{"@type":"WebSite","@id":"https:\/\/steinzauber-online.de\/#website","url":"https:\/\/steinzauber-online.de\/","name":"Steinzauber\u00ae","description":"Schmuck aus edlem Stein","publisher":{"@id":"https:\/\/steinzauber-online.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/steinzauber-online.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/steinzauber-online.de\/#organization","name":"Steinzauber","url":"https:\/\/steinzauber-online.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","width":500,"height":262,"caption":"Steinzauber"},"image":{"@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/Steinzauber\/","https:\/\/instagram.com\/steinzauber_schmuck?igshid=1fr2q2be784ld"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product\/6945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media\/6946"}],"wp:attachment":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media?parent=6945"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=6945"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=6945"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=6945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}