{"id":6517,"date":"2020-03-05T16:35:30","date_gmt":"2020-03-05T15:35:30","guid":{"rendered":"https:\/\/steinzauber-online.de\/?post_type=product&#038;p=6517"},"modified":"2025-05-14T12:55:46","modified_gmt":"2025-05-14T11:55:46","slug":"turmalin-ring-in-sterlingsilber-08","status":"publish","type":"product","link":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/","title":{"rendered":"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60)"},"content":{"rendered":"<p><strong>Herrlicher Turmalin Ring in 925er Sterlingsilber<\/strong><\/p>\n<p>Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit.<\/p>\n<p>Der Name stammt vom singhalesischen Wort <i>thuramali<\/i> bzw. <i>thoramalli<\/i> ab, das man in Sri Lanka allgemein f\u00fcr bunte Schmucksteine verwendete. Turmaline gibt es in vielen Farbvariationen, sie kann sogar entlang der L\u00e4ngsachse eines einzelnen Kristalls variieren. H\u00e4ufig kommen blaue, gr\u00fcne, rote, rosafarbene, braune oder schwarze Varianten vor.<\/p>\n<p>Sie kaufen genau den Ring, den Sie auf diesen Fotos sehen. Er hat die Gr\u00f6\u00dfe 19,0 mm im Innendurchmesser, was der Gr\u00f6\u00dfe 60 entspricht. Der Turmalin besitzt eine Gr\u00f6\u00dfe von ca. 9 x 7 mm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Herrlicher Turmalin Ring in 925er Sterlingsilber Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Der Name stammt vom singhalesischen Wort thuramali bzw. thoramalli ab, das man in Sri Lanka allgemein f\u00fcr bunte Schmucksteine verwendete. Turmaline gibt es in vielen Farbvariationen, sie kann sogar entlang der L\u00e4ngsachse eines einzelnen Kristalls [&#8230;]<\/p>\n","protected":false},"featured_media":6518,"template":"","meta":[],"product_brand":[],"product_cat":[730],"product_tag":[737,630,740,203,731,30,451],"class_list":{"0":"post-6517","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-silber-mit-stein","7":"product_tag-elbait","8":"product_tag-ring","9":"product_tag-rubellit","10":"product_tag-silber","11":"product_tag-silberring","12":"product_tag-sterlingsilber","13":"product_tag-turmalin","15":"first","16":"outofstock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60) - Steinzauber\u00ae<\/title>\n<meta name=\"description\" content=\"Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Er hat die Gr\u00f6\u00dfe 19,0 mm (60).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60) - Steinzauber\u00ae\" \/>\n<meta property=\"og:description\" content=\"Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Er hat die Gr\u00f6\u00dfe 19,0 mm (60).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/\" \/>\n<meta property=\"og:site_name\" content=\"Steinzauber\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/Steinzauber\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T11:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/03\/Ring_Turmalin_Silber_RITU108a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/\",\"name\":\"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60) - Steinzauber\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Ring_Turmalin_Silber_RITU108a.jpg\",\"datePublished\":\"2020-03-05T15:35:30+00:00\",\"dateModified\":\"2025-05-14T11:55:46+00:00\",\"description\":\"Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Er hat die Gr\u00f6\u00dfe 19,0 mm (60).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/#primaryimage\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Ring_Turmalin_Silber_RITU108a.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Ring_Turmalin_Silber_RITU108a.jpg\",\"width\":800,\"height\":800,\"caption\":\"Turmalin Ring in Sterlingsilber\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/turmalin-ring-in-sterlingsilber-08\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"name\":\"Steinzauber\u00ae\",\"description\":\"Schmuck aus edlem Stein\",\"publisher\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/steinzauber-online.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\",\"name\":\"Steinzauber\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"width\":500,\"height\":262,\"caption\":\"Steinzauber\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/Steinzauber\\\/\",\"https:\\\/\\\/instagram.com\\\/steinzauber_schmuck?igshid=1fr2q2be784ld\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60) - Steinzauber\u00ae","description":"Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Er hat die Gr\u00f6\u00dfe 19,0 mm (60).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/","og_locale":"de_DE","og_type":"article","og_title":"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60) - Steinzauber\u00ae","og_description":"Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Er hat die Gr\u00f6\u00dfe 19,0 mm (60).","og_url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/","og_site_name":"Steinzauber\u00ae","article_publisher":"https:\/\/de-de.facebook.com\/Steinzauber\/","article_modified_time":"2025-05-14T11:55:46+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/03\/Ring_Turmalin_Silber_RITU108a.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/","url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/","name":"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60) - Steinzauber\u00ae","isPartOf":{"@id":"https:\/\/steinzauber-online.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/#primaryimage"},"image":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/#primaryimage"},"thumbnailUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/03\/Ring_Turmalin_Silber_RITU108a.jpg","datePublished":"2020-03-05T15:35:30+00:00","dateModified":"2025-05-14T11:55:46+00:00","description":"Ein sehr sch\u00f6ner Ring mit einem hochwertigen, wundersch\u00f6nen Turmalin in der rosanen Variet\u00e4t Rubellit. Er hat die Gr\u00f6\u00dfe 19,0 mm (60).","breadcrumb":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/#primaryimage","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/03\/Ring_Turmalin_Silber_RITU108a.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2020\/03\/Ring_Turmalin_Silber_RITU108a.jpg","width":800,"height":800,"caption":"Turmalin Ring in Sterlingsilber"},{"@type":"BreadcrumbList","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/turmalin-ring-in-sterlingsilber-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/steinzauber-online.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/steinzauber-online.de\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Turmalin Ring in Sterlingsilber, Gr\u00f6\u00dfe 19,0mm (60)"}]},{"@type":"WebSite","@id":"https:\/\/steinzauber-online.de\/#website","url":"https:\/\/steinzauber-online.de\/","name":"Steinzauber\u00ae","description":"Schmuck aus edlem Stein","publisher":{"@id":"https:\/\/steinzauber-online.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/steinzauber-online.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/steinzauber-online.de\/#organization","name":"Steinzauber","url":"https:\/\/steinzauber-online.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","width":500,"height":262,"caption":"Steinzauber"},"image":{"@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/Steinzauber\/","https:\/\/instagram.com\/steinzauber_schmuck?igshid=1fr2q2be784ld"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product\/6517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media\/6518"}],"wp:attachment":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media?parent=6517"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=6517"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=6517"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=6517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}