{"id":19267,"date":"2023-11-06T14:40:33","date_gmt":"2023-11-06T13:40:33","guid":{"rendered":"https:\/\/steinzauber-online.de\/?post_type=product&#038;p=19267"},"modified":"2025-12-17T20:09:31","modified_gmt":"2025-12-17T19:09:31","slug":"granat-ring-facettiert-aus-925-silber","status":"publish","type":"product","link":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/","title":{"rendered":"Granat Ring facettiert aus 925 Silber"},"content":{"rendered":"<p>Extravaganter Ring aus 925 Sterling Silber mit facettiertem Granat. Durch den perfekten Facettenschliff bricht sich das Licht und verleiht diesem Ring sein wunderbares warmes, rotes Funkeln. Besonders sch\u00f6n hebt sich die hochgl\u00e4nzende Fassung der Granat Steine von der matt geb\u00fcrsteten Ringschiene ab. Ein Ring der garantiert die Blicke auf sich ziehen wird.<br \/>\nOb zu einem sportlichen Outfit mit Jeans oder zu festlicher Garderobe, dieser Ring passt zu jeder Kleidung und jedem Anlass.<br \/>\nDieser wundersch\u00f6ne Schmuck eignet sich hervorragend um sich selbst etwas sch\u00f6nes zu g\u00f6nnen, oder als Geschenk f\u00fcr einen besonderen Menschen, Schmuck macht einfach gl\u00fccklich.<br \/>\nAlle Schmuckst\u00fccke werden bei uns mit h\u00f6chster Sorgfalt liebevoll verpackt.<\/p>\n<p>\u2605 Edelsteingr\u00f6\u00dfe:<br \/>\n\u2713 incl. Fassung: Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca.: 8,5 x 6,5 mm<\/p>\n<p>\u2605 Ma\u00dfe:<br \/>\n\u2713 Breite der Ringschiene: Front ca. 12 mm R\u00fcckseite ca. 10 mm<\/p>\n<p>\u2605 Das Material:<br \/>\n\u2713 925 Sterlingsilber, z.T. matt geb\u00fcrstet<\/p>\n<p>\u2713 facettierter Granat<\/p>\n<p>\u2605 Lieferung:<br \/>\n\u2713 Dieses Schmuckst\u00fcck liefern wir euch sorgf\u00e4ltig und liebevoll verpackt mit versichertem Versand und Sendeverfolgung.<\/p>\n<p>\u2605 Service:<br \/>\n\u2713 Unser Service endet nicht mit dem Verkauf, unsere Manufaktur bietet Ihnen auch eine professionelle Schmuckreinigung der bei uns gekauften Schmuckst\u00fccke an. Dazu bitten wir vorab um Kontaktaufnahme.<\/p>\n<p>\u2713 Auf Wunsch verpacken wir Ihre Bestellung auch als Geschenk, der wir auch gerne eine pers\u00f6nliche Nachricht von Ihnen zuf\u00fcgen.<\/p>\n<p>\u2605 Herstellung:<br \/>\n\u2713 Jedes Schmuckst\u00fcck wird traditionell mit h\u00f6chster Pr\u00e4zession bis ins kleinste Detail von Hand gefertigt.<\/p>\n<p>\u2713 Bei allen Edelsteinen handelt es sich um Steine h\u00f6chster Qualit\u00e4t<\/p>\n<p>\u2713 Alle Schmuckst\u00fccke sind mit einem Anlaufschutz versehen, allerdings liegt es in der Natur, dass mit der Zeit doch eine gewisse Oxydation sichtbar wird.<\/p>\n<p>\u2713 Alle Schmuckst\u00fccke werden mit Liebe hergestellt und wir freuen uns sehr \u00fcber R\u00fcckmeldungen und zufriedene Kunden.<\/p>\n<p>\u2713 Wir sind erst dann gl\u00fccklich wenn es uns gelungen ist, euch (oder die von euch Beschenkten) gl\u00fccklich zu machen.<\/p>\n<p>Eure Petra von Steinzauber<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extravaganter Ring aus 925 Sterling Silber mit facettiertem Granat. Durch den perfekten Facettenschliff bricht sich das Licht und verleiht diesem Ring sein wunderbares warmes, rotes Funkeln. Besonders sch\u00f6n hebt sich die hochgl\u00e4nzende Fassung der Granat Steine von der matt geb\u00fcrsteten Ringschiene ab. Ein Ring der garantiert die Blicke auf sich ziehen wird. Ob zu einem [&#8230;]<\/p>\n","protected":false},"featured_media":19283,"template":"","meta":[],"product_brand":[],"product_cat":[730,603],"product_tag":[1128,1202,916,1760,1761,1762,731,1212],"class_list":{"0":"post-19267","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-silber-mit-stein","7":"product_cat-neue-artikel-bei-steinzauber","8":"product_tag-925-sterling-silber","9":"product_tag-facettenschliff","10":"product_tag-geschenk","11":"product_tag-ring-aus-granat","12":"product_tag-ring-granat","13":"product_tag-silber-ring-granat","14":"product_tag-silberring","15":"product_tag-statement-ring","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Granat Ring facettiert aus 925 Silber - Steinzauber\u00ae<\/title>\n<meta name=\"description\" content=\"Wundersch\u00f6ner Ring aus 925 Sterling Silber mit facettiertem Granat. Der Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca. 8,5 x 6,5 mm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Granat Ring facettiert aus 925 Silber - Steinzauber\u00ae\" \/>\n<meta property=\"og:description\" content=\"Wundersch\u00f6ner Ring aus 925 Sterling Silber mit facettiertem Granat. Der Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca. 8,5 x 6,5 mm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/\" \/>\n<meta property=\"og:site_name\" content=\"Steinzauber\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/Steinzauber\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T19:09:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2023\/11\/RIGR-A-fac-SM8-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2221\" \/>\n\t<meta property=\"og:image:height\" content=\"1669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/\",\"name\":\"Granat Ring facettiert aus 925 Silber - Steinzauber\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/RIGR-A-fac-SM8-5.jpg\",\"datePublished\":\"2023-11-06T13:40:33+00:00\",\"dateModified\":\"2025-12-17T19:09:31+00:00\",\"description\":\"Wundersch\u00f6ner Ring aus 925 Sterling Silber mit facettiertem Granat. Der Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca. 8,5 x 6,5 mm.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/#primaryimage\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/RIGR-A-fac-SM8-5.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/RIGR-A-fac-SM8-5.jpg\",\"width\":2221,\"height\":1669,\"caption\":\"Ring Granat 925 Sterling Silber\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/produkt\\\/granat-ring-facettiert-aus-925-silber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/steinzauber-online.de\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Granat Ring facettiert aus 925 Silber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#website\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"name\":\"Steinzauber\u00ae\",\"description\":\"Schmuck aus edlem Stein\",\"publisher\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/steinzauber-online.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#organization\",\"name\":\"Steinzauber\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"contentUrl\":\"https:\\\/\\\/steinzauber-online.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo_500-262.jpg\",\"width\":500,\"height\":262,\"caption\":\"Steinzauber\"},\"image\":{\"@id\":\"https:\\\/\\\/steinzauber-online.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/Steinzauber\\\/\",\"https:\\\/\\\/instagram.com\\\/steinzauber_schmuck?igshid=1fr2q2be784ld\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Granat Ring facettiert aus 925 Silber - Steinzauber\u00ae","description":"Wundersch\u00f6ner Ring aus 925 Sterling Silber mit facettiertem Granat. Der Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca. 8,5 x 6,5 mm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/","og_locale":"de_DE","og_type":"article","og_title":"Granat Ring facettiert aus 925 Silber - Steinzauber\u00ae","og_description":"Wundersch\u00f6ner Ring aus 925 Sterling Silber mit facettiertem Granat. Der Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca. 8,5 x 6,5 mm.","og_url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/","og_site_name":"Steinzauber\u00ae","article_publisher":"https:\/\/de-de.facebook.com\/Steinzauber\/","article_modified_time":"2025-12-17T19:09:31+00:00","og_image":[{"width":2221,"height":1669,"url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2023\/11\/RIGR-A-fac-SM8-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/","url":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/","name":"Granat Ring facettiert aus 925 Silber - Steinzauber\u00ae","isPartOf":{"@id":"https:\/\/steinzauber-online.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/#primaryimage"},"image":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/#primaryimage"},"thumbnailUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2023\/11\/RIGR-A-fac-SM8-5.jpg","datePublished":"2023-11-06T13:40:33+00:00","dateModified":"2025-12-17T19:09:31+00:00","description":"Wundersch\u00f6ner Ring aus 925 Sterling Silber mit facettiertem Granat. Der Durchmesser der kleinen runden Steine ca. 4 mm, Tr\u00e4nenform ca. 8,5 x 6,5 mm.","breadcrumb":{"@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/#primaryimage","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2023\/11\/RIGR-A-fac-SM8-5.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2023\/11\/RIGR-A-fac-SM8-5.jpg","width":2221,"height":1669,"caption":"Ring Granat 925 Sterling Silber"},{"@type":"BreadcrumbList","@id":"https:\/\/steinzauber-online.de\/index.php\/produkt\/granat-ring-facettiert-aus-925-silber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/steinzauber-online.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/steinzauber-online.de\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Granat Ring facettiert aus 925 Silber"}]},{"@type":"WebSite","@id":"https:\/\/steinzauber-online.de\/#website","url":"https:\/\/steinzauber-online.de\/","name":"Steinzauber\u00ae","description":"Schmuck aus edlem Stein","publisher":{"@id":"https:\/\/steinzauber-online.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/steinzauber-online.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/steinzauber-online.de\/#organization","name":"Steinzauber","url":"https:\/\/steinzauber-online.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/","url":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","contentUrl":"https:\/\/steinzauber-online.de\/wp-content\/uploads\/2021\/02\/Logo_500-262.jpg","width":500,"height":262,"caption":"Steinzauber"},"image":{"@id":"https:\/\/steinzauber-online.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/Steinzauber\/","https:\/\/instagram.com\/steinzauber_schmuck?igshid=1fr2q2be784ld"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product\/19267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media\/19283"}],"wp:attachment":[{"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/media?parent=19267"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=19267"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=19267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steinzauber-online.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=19267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}